{"id":958,"date":"2022-11-04T09:07:17","date_gmt":"2022-11-04T08:07:17","guid":{"rendered":"https:\/\/www.lesjardinsdesaintehildegarde.com\/non%20class\u00e9\/chataignes-bio-sauvage-epluchees-500g\/"},"modified":"2026-05-13T14:19:02","modified_gmt":"2026-05-13T12:19:02","slug":"chataignes-bio-sauvage-epluchees-500g","status":"publish","type":"product","link":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/","title":{"rendered":"CHATAIGNES BIO EPLUCHEES 500G*"},"content":{"rendered":"<p>CH\u00c2TAIGNES BIO S\u00c9CH\u00c9ES \u00c9PLUCH\u00c9ES  500 G  * (21.80\u20ac \/ kg)<\/p>\n<p>S\u00e9ch\u00e9es et \u00e9pluch\u00e9es<\/p>\n<p>* issu de l&#8217;agriculture biologique &#8211; Origine France<\/p>\n<p>500g de ch\u00e2taignes s\u00e9ch\u00e9es \u00e9quivalent \u00e0 1,5 kg de fra\u00eeches.<\/p>\n<p>Ingr\u00e9dients: Ch\u00e2taignes des C\u00e9vennes Bio<\/p>\n<p>Conseils d&#8217;utilisation :<\/p>\n<p>Laisser tremper les ch\u00e2taignes une nuit, cuire 1\/2 heure \u00e0 3\/4 heure.<\/p>\n<p>Utiliser pour accompagner une viande ou mettre dans une soupe etc&#8230;<\/p>\n<p>Se r\u00e9f\u00e9rer aux \u00e9crits de Sainte Hildegarde de Bingen : PHYSICA Ch.XII : LE CH\u00c2TAIGNIER<\/p>\n<p>Garder \u00e0 l&#8217;abri du soleil dans un endroit propre et sec.<\/p>\n<p>Valeurs nutritionnelles pour 100g :<\/p>\n<p>Energie 364 kcal \/ 1546 kJ<\/p>\n<p>Lipides 1.1g dont acides gras satur\u00e9s 0.2g<\/p>\n<p>Glucides 82.5g dont sucres 33.2g<\/p>\n<p>Prot\u00e9ines 0.6g<\/p>\n<p>Fibres 5.1g<\/p>\n<p>Sel 0.01g<\/p>\n<p>Photo(s) non contractuelles:<\/p>\n<p>L&#8217;origine naturelle de ce produit ne nous permet pas de vous garantir un aspect strictement identique d &#8216;un lot \u00e0 l&#8217;autre.<\/p>\n<p>En effet, de sensibles variations de couleurs, d&#8217;aspect, de texture, de go\u00fbt, de coupe, peuvent intervenir selon le climat, et selon les diff\u00e9rentes \u00e9tapes qui succ\u00e8dent \u00e0 la r\u00e9colte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CH\u00c2TAIGNES BIO S\u00c9CH\u00c9ES \u00c9PLUCH\u00c9ES 500 G * (21.80\u20ac \/ kg) S\u00e9ch\u00e9es et \u00e9pluch\u00e9es * issu de l&#8217;agriculture biologique &#8211; Origine France 500g de ch\u00e2taignes s\u00e9ch\u00e9es \u00e9quivalent \u00e0 1,5 kg de fra\u00eeches. Ingr\u00e9dients: Ch\u00e2taignes des C\u00e9vennes Bio Conseils d&#8217;utilisation : Laisser tremper les ch\u00e2taignes une nuit, cuire 1\/2 heure \u00e0 3\/4 heure. Utiliser pour accompagner une [&hellip;]<\/p>\n","protected":false},"featured_media":66843,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[30,55],"product_tag":[49],"class_list":{"0":"post-958","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-epeautres-alimentation","7":"product_cat-fruits-et-preparations-a-base-de-fruits","8":"product_tag-produit-bio","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHATAIGNES BIO EPLUCHEES 500G* - Les Jardins de Sainte-Hildegarde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHATAIGNES BIO EPLUCHEES 500G* - Les Jardins de Sainte-Hildegarde\" \/>\n<meta property=\"og:description\" content=\"CH\u00c2TAIGNES BIO S\u00c9CH\u00c9ES \u00c9PLUCH\u00c9ES 500 G * (21.80\u20ac \/ kg) S\u00e9ch\u00e9es et \u00e9pluch\u00e9es * issu de l&#8217;agriculture biologique &#8211; Origine France 500g de ch\u00e2taignes s\u00e9ch\u00e9es \u00e9quivalent \u00e0 1,5 kg de fra\u00eeches. Ingr\u00e9dients: Ch\u00e2taignes des C\u00e9vennes Bio Conseils d&#8217;utilisation : Laisser tremper les ch\u00e2taignes une nuit, cuire 1\/2 heure \u00e0 3\/4 heure. Utiliser pour accompagner une [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Jardins de Sainte-Hildegarde\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:19:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2023\/07\/15053-chataignes-sechees-bio-500g.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/\",\"url\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/\",\"name\":\"CHATAIGNES BIO EPLUCHEES 500G* - Les Jardins de Sainte-Hildegarde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/15053-chataignes-sechees-bio-500g.jpg\",\"datePublished\":\"2022-11-04T08:07:17+00:00\",\"dateModified\":\"2026-05-13T12:19:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/15053-chataignes-sechees-bio-500g.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/15053-chataignes-sechees-bio-500g.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Ch\u00e2taignes des C\u00e9vennes Bio \\\"blanchettes\\\" d\u00e9shydrat\u00e9es par s\u00e9chage au feu de bois. Sachet de 500g, recommand\u00e9 par sainte Hildegarde de Bingen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/espelta-alimentacion\\\/frutos-y-preparaciones-a-base-de-frutos\\\/chataignes-bio-sauvage-epluchees-500g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHATAIGNES BIO EPLUCHEES 500G*\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/\",\"name\":\"Les Jardins de Sainte-Hildegarde\",\"description\":\"Viriditas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/#organization\",\"name\":\"Les Jardins de Sainte-Hildegarde\",\"url\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-2022.png\",\"contentUrl\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-2022.png\",\"width\":365,\"height\":90,\"caption\":\"Les Jardins de Sainte-Hildegarde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesjardinsdesaintehildegarde.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHATAIGNES BIO EPLUCHEES 500G* - Les Jardins de Sainte-Hildegarde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/","og_locale":"es_ES","og_type":"article","og_title":"CHATAIGNES BIO EPLUCHEES 500G* - Les Jardins de Sainte-Hildegarde","og_description":"CH\u00c2TAIGNES BIO S\u00c9CH\u00c9ES \u00c9PLUCH\u00c9ES 500 G * (21.80\u20ac \/ kg) S\u00e9ch\u00e9es et \u00e9pluch\u00e9es * issu de l&#8217;agriculture biologique &#8211; Origine France 500g de ch\u00e2taignes s\u00e9ch\u00e9es \u00e9quivalent \u00e0 1,5 kg de fra\u00eeches. Ingr\u00e9dients: Ch\u00e2taignes des C\u00e9vennes Bio Conseils d&#8217;utilisation : Laisser tremper les ch\u00e2taignes une nuit, cuire 1\/2 heure \u00e0 3\/4 heure. Utiliser pour accompagner une [&hellip;]","og_url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/","og_site_name":"Les Jardins de Sainte-Hildegarde","article_modified_time":"2026-05-13T12:19:02+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2023\/07\/15053-chataignes-sechees-bio-500g.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/","url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/","name":"CHATAIGNES BIO EPLUCHEES 500G* - Les Jardins de Sainte-Hildegarde","isPartOf":{"@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/#primaryimage"},"image":{"@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2023\/07\/15053-chataignes-sechees-bio-500g.jpg","datePublished":"2022-11-04T08:07:17+00:00","dateModified":"2026-05-13T12:19:02+00:00","breadcrumb":{"@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/#primaryimage","url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2023\/07\/15053-chataignes-sechees-bio-500g.jpg","contentUrl":"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2023\/07\/15053-chataignes-sechees-bio-500g.jpg","width":1200,"height":1200,"caption":"Ch\u00e2taignes des C\u00e9vennes Bio \"blanchettes\" d\u00e9shydrat\u00e9es par s\u00e9chage au feu de bois. Sachet de 500g, recommand\u00e9 par sainte Hildegarde de Bingen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/espelta-alimentacion\/frutos-y-preparaciones-a-base-de-frutos\/chataignes-bio-sauvage-epluchees-500g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"CHATAIGNES BIO EPLUCHEES 500G*"}]},{"@type":"WebSite","@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/#website","url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/","name":"Les Jardins de Sainte-Hildegarde","description":"Viriditas","publisher":{"@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/#organization","name":"Les Jardins de Sainte-Hildegarde","url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2022\/11\/logo-2022.png","contentUrl":"https:\/\/www.lesjardinsdesaintehildegarde.com\/wp-content\/uploads\/2022\/11\/logo-2022.png","width":365,"height":90,"caption":"Les Jardins de Sainte-Hildegarde"},"image":{"@id":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/product\/958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/comments?post=958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/media\/66843"}],"wp:attachment":[{"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/media?parent=958"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/product_brand?post=958"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/product_cat?post=958"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lesjardinsdesaintehildegarde.com\/es\/wp-json\/wp\/v2\/product_tag?post=958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}